{"id":86009,"date":"2023-05-04T14:00:07","date_gmt":"2023-05-04T12:00:07","guid":{"rendered":"https:\/\/www.tirolergoldschmied.it\/produkt\/pendente-forest-acorn-2\/"},"modified":"2025-09-19T12:33:58","modified_gmt":"2025-09-19T10:33:58","slug":"ole-lynggaard-copenhagen-forest-collane-a2920-404","status":"publish","type":"product","link":"https:\/\/www.tirolergoldschmied.it\/it\/shop\/ole-lynggaard-copenhagen\/ole-lynggaard-copenhagen-forest-collane-a2920-404\/","title":{"rendered":"Pendente Forest Acorn"},"content":{"rendered":"<div class=\"berocket_ww_container\">\r\n    <div class=\"berocket_ww_empty\">\r\n        <p>Il Dreambox \u00e8 vuoto.<\/p>\r\n    <\/div>\r\n<\/div>\r\n<script>\r\njQuery('.berocket_ww_container').each( function( i, o ) {\r\n    if ( jQuery(o).height() + 20 < jQuery(o).find('.berocket_ww_ul_container').height() && jQuery(o).find('.berocket_ww_show_all').length ) {\r\n        jQuery(o).find('.berocket_ww_show_all').show();\r\n    } else if( ! jQuery(o).find('.berocket_ww_show_all').length ) {\r\n        var $scroll_block = jQuery(o).find('.berocket_ww_list');\r\n        $scroll_block.css( {maxHeight: 'initial'} );\r\n    }\r\n});\r\n<\/script>\r\n","protected":false},"excerpt":{"rendered":"<p>750 \/ 18 kt oro giallo lucido, 1 Falcon Eye Acorn, lunghezza 2,9cm<\/p>\n","protected":false},"featured_media":86013,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false},"product_brand":[965],"product_cat":[230,527,200,251],"product_tag":[],"product_occasion":[236,287,263,188,182,185],"product_material":[227],"product_material_color":[],"product_model":[197],"product_alloy":[206],"product_jewelry":[257,254],"product_size":[],"product_length":[],"product_collection":[1411],"product_metal_color":[1271],"class_list":{"0":"post-86009","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_brand-ole-lynggaard-copenhagen","7":"product_cat-gioielli-con-pietre-preziose","8":"product_cat-gioielli-da-caccia","9":"product_cat-gioielli-in-oro","10":"product_cat-gioielli-per-abiti-tradizionali-e-dirndl","11":"product_occasion-amicizia","12":"product_occasion-cresima","13":"product_occasion-diploma-di-maturita-laurea","14":"product_occasion-festa-della-mamma","15":"product_occasion-nascita","16":"product_occasion-san-valentino","17":"product_material-gemme-it","18":"product_model-donne-it","19":"product_alloy-750-18-kt-it","20":"product_jewelry-collane","21":"product_jewelry-anhaenger-it","22":"product_collection-forest","23":"product_metal_color-oro-giallo-it","25":"first","26":"outofstock","27":"taxable","28":"shipping-taxable","29":"purchasable","30":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ole Lynggaard Copenhagen - Forest Acorn - Pendente - oro giallo<\/title>\n<meta name=\"description\" content=\"750 \/ 18 kt oro giallo lucido, 1 Falcon Eye Acorn, lunghezza 2,9cm\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tirolergoldschmied.it\/it\/shop\/ole-lynggaard-copenhagen\/ole-lynggaard-copenhagen-forest-collane-a2920-404\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ole Lynggaard Copenhagen - Forest Acorn - Pendente - oro giallo\" \/>\n<meta property=\"og:description\" content=\"750 \/ 18 kt oro giallo lucido, 1 Falcon Eye Acorn, lunghezza 2,9cm\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tirolergoldschmied.it\/it\/shop\/ole-lynggaard-copenhagen\/ole-lynggaard-copenhagen-forest-collane-a2920-404\/\" \/>\n<meta property=\"og:site_name\" content=\"Tiroler Goldschmied\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-19T10:33:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/static.tirolergoldschmied.it\/39543ca551be492a\/2023\/05\/86013\/c\/fit-in\/0x0\/filters:no_upscale()\/filters:strip_exif()\/a2920-404.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tirolergoldschmied.it\\\/it\\\/shop\\\/ole-lynggaard-copenhagen\\\/ole-lynggaard-copenhagen-forest-collane-a2920-404\\\/\",\"url\":\"https:\\\/\\\/www.tirolergoldschmied.it\\\/it\\\/shop\\\/ole-lynggaard-copenhagen\\\/ole-lynggaard-copenhagen-forest-collane-a2920-404\\\/\",\"name\":\"Ole Lynggaard Copenhagen - Forest Acorn - Pendente - oro giallo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tirolergoldschmied.it\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tirolergoldschmied.it\\\/it\\\/shop\\\/ole-lynggaard-copenhagen\\\/ole-lynggaard-copenhagen-forest-collane-a2920-404\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tirolergoldschmied.it\\\/it\\\/shop\\\/ole-lynggaard-copenhagen\\\/ole-lynggaard-copenhagen-forest-collane-a2920-404\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/static.tirolergoldschmied.it\\\/39543ca551be492a\\\/2023\\\/05\\\/86013\\\/c\\\/fit-in\\\/0x0\\\/filters:no_upscale()\\\/filters:strip_exif()\\\/a2920-404.jpg\",\"datePublished\":\"2023-05-04T12:00:07+00:00\",\"dateModified\":\"2025-09-19T10:33:58+00:00\",\"description\":\"750 \\\/ 18 kt oro giallo lucido, 1 Falcon Eye Acorn, lunghezza 2,9cm\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tirolergoldschmied.it\\\/it\\\/shop\\\/ole-lynggaard-copenhagen\\\/ole-lynggaard-copenhagen-forest-collane-a2920-404\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tirolergoldschmied.it\\\/it\\\/shop\\\/ole-lynggaard-copenhagen\\\/ole-lynggaard-copenhagen-forest-collane-a2920-404\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tirolergoldschmied.it\\\/it\\\/shop\\\/ole-lynggaard-copenhagen\\\/ole-lynggaard-copenhagen-forest-collane-a2920-404\\\/#primaryimage\",\"url\":\"https:\\\/\\\/static.tirolergoldschmied.it\\\/39543ca551be492a\\\/2023\\\/05\\\/86013\\\/c\\\/fit-in\\\/0x0\\\/filters:no_upscale()\\\/filters:strip_exif()\\\/a2920-404.jpg\",\"contentUrl\":\"https:\\\/\\\/static.tirolergoldschmied.it\\\/39543ca551be492a\\\/2023\\\/05\\\/86013\\\/c\\\/fit-in\\\/0x0\\\/filters:no_upscale()\\\/filters:strip_exif()\\\/a2920-404.jpg\",\"width\":1000,\"height\":1000},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tirolergoldschmied.it\\\/it\\\/shop\\\/ole-lynggaard-copenhagen\\\/ole-lynggaard-copenhagen-forest-collane-a2920-404\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.tirolergoldschmied.it\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/www.tirolergoldschmied.it\\\/it\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Pendente Forest Acorn\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tirolergoldschmied.it\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/www.tirolergoldschmied.it\\\/it\\\/\",\"name\":\"Tiroler Goldschmied\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tirolergoldschmied.it\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ole Lynggaard Copenhagen - Forest Acorn - Pendente - oro giallo","description":"750 \/ 18 kt oro giallo lucido, 1 Falcon Eye Acorn, lunghezza 2,9cm","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tirolergoldschmied.it\/it\/shop\/ole-lynggaard-copenhagen\/ole-lynggaard-copenhagen-forest-collane-a2920-404\/","og_locale":"it_IT","og_type":"article","og_title":"Ole Lynggaard Copenhagen - Forest Acorn - Pendente - oro giallo","og_description":"750 \/ 18 kt oro giallo lucido, 1 Falcon Eye Acorn, lunghezza 2,9cm","og_url":"https:\/\/www.tirolergoldschmied.it\/it\/shop\/ole-lynggaard-copenhagen\/ole-lynggaard-copenhagen-forest-collane-a2920-404\/","og_site_name":"Tiroler Goldschmied","article_modified_time":"2025-09-19T10:33:58+00:00","og_image":[{"width":1000,"height":1000,"url":"https:\/\/static.tirolergoldschmied.it\/39543ca551be492a\/2023\/05\/86013\/c\/fit-in\/0x0\/filters:no_upscale()\/filters:strip_exif()\/a2920-404.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.tirolergoldschmied.it\/it\/shop\/ole-lynggaard-copenhagen\/ole-lynggaard-copenhagen-forest-collane-a2920-404\/","url":"https:\/\/www.tirolergoldschmied.it\/it\/shop\/ole-lynggaard-copenhagen\/ole-lynggaard-copenhagen-forest-collane-a2920-404\/","name":"Ole Lynggaard Copenhagen - Forest Acorn - Pendente - oro giallo","isPartOf":{"@id":"https:\/\/www.tirolergoldschmied.it\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tirolergoldschmied.it\/it\/shop\/ole-lynggaard-copenhagen\/ole-lynggaard-copenhagen-forest-collane-a2920-404\/#primaryimage"},"image":{"@id":"https:\/\/www.tirolergoldschmied.it\/it\/shop\/ole-lynggaard-copenhagen\/ole-lynggaard-copenhagen-forest-collane-a2920-404\/#primaryimage"},"thumbnailUrl":"https:\/\/static.tirolergoldschmied.it\/39543ca551be492a\/2023\/05\/86013\/c\/fit-in\/0x0\/filters:no_upscale()\/filters:strip_exif()\/a2920-404.jpg","datePublished":"2023-05-04T12:00:07+00:00","dateModified":"2025-09-19T10:33:58+00:00","description":"750 \/ 18 kt oro giallo lucido, 1 Falcon Eye Acorn, lunghezza 2,9cm","breadcrumb":{"@id":"https:\/\/www.tirolergoldschmied.it\/it\/shop\/ole-lynggaard-copenhagen\/ole-lynggaard-copenhagen-forest-collane-a2920-404\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tirolergoldschmied.it\/it\/shop\/ole-lynggaard-copenhagen\/ole-lynggaard-copenhagen-forest-collane-a2920-404\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tirolergoldschmied.it\/it\/shop\/ole-lynggaard-copenhagen\/ole-lynggaard-copenhagen-forest-collane-a2920-404\/#primaryimage","url":"https:\/\/static.tirolergoldschmied.it\/39543ca551be492a\/2023\/05\/86013\/c\/fit-in\/0x0\/filters:no_upscale()\/filters:strip_exif()\/a2920-404.jpg","contentUrl":"https:\/\/static.tirolergoldschmied.it\/39543ca551be492a\/2023\/05\/86013\/c\/fit-in\/0x0\/filters:no_upscale()\/filters:strip_exif()\/a2920-404.jpg","width":1000,"height":1000},{"@type":"BreadcrumbList","@id":"https:\/\/www.tirolergoldschmied.it\/it\/shop\/ole-lynggaard-copenhagen\/ole-lynggaard-copenhagen-forest-collane-a2920-404\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.tirolergoldschmied.it\/it\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/www.tirolergoldschmied.it\/it\/shop\/"},{"@type":"ListItem","position":3,"name":"Pendente Forest Acorn"}]},{"@type":"WebSite","@id":"https:\/\/www.tirolergoldschmied.it\/it\/#website","url":"https:\/\/www.tirolergoldschmied.it\/it\/","name":"Tiroler Goldschmied","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tirolergoldschmied.it\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"}]}},"_links":{"self":[{"href":"https:\/\/www.tirolergoldschmied.it\/it\/wp-json\/wp\/v2\/product\/86009","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tirolergoldschmied.it\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.tirolergoldschmied.it\/it\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tirolergoldschmied.it\/it\/wp-json\/wp\/v2\/comments?post=86009"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tirolergoldschmied.it\/it\/wp-json\/wp\/v2\/media\/86013"}],"wp:attachment":[{"href":"https:\/\/www.tirolergoldschmied.it\/it\/wp-json\/wp\/v2\/media?parent=86009"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.tirolergoldschmied.it\/it\/wp-json\/wp\/v2\/product_brand?post=86009"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.tirolergoldschmied.it\/it\/wp-json\/wp\/v2\/product_cat?post=86009"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.tirolergoldschmied.it\/it\/wp-json\/wp\/v2\/product_tag?post=86009"},{"taxonomy":"product_occasion","embeddable":true,"href":"https:\/\/www.tirolergoldschmied.it\/it\/wp-json\/wp\/v2\/product_occasion?post=86009"},{"taxonomy":"product_material","embeddable":true,"href":"https:\/\/www.tirolergoldschmied.it\/it\/wp-json\/wp\/v2\/product_material?post=86009"},{"taxonomy":"product_material_color","embeddable":true,"href":"https:\/\/www.tirolergoldschmied.it\/it\/wp-json\/wp\/v2\/product_material_color?post=86009"},{"taxonomy":"product_model","embeddable":true,"href":"https:\/\/www.tirolergoldschmied.it\/it\/wp-json\/wp\/v2\/product_model?post=86009"},{"taxonomy":"product_alloy","embeddable":true,"href":"https:\/\/www.tirolergoldschmied.it\/it\/wp-json\/wp\/v2\/product_alloy?post=86009"},{"taxonomy":"product_jewelry","embeddable":true,"href":"https:\/\/www.tirolergoldschmied.it\/it\/wp-json\/wp\/v2\/product_jewelry?post=86009"},{"taxonomy":"product_size","embeddable":true,"href":"https:\/\/www.tirolergoldschmied.it\/it\/wp-json\/wp\/v2\/product_size?post=86009"},{"taxonomy":"product_length","embeddable":true,"href":"https:\/\/www.tirolergoldschmied.it\/it\/wp-json\/wp\/v2\/product_length?post=86009"},{"taxonomy":"product_collection","embeddable":true,"href":"https:\/\/www.tirolergoldschmied.it\/it\/wp-json\/wp\/v2\/product_collection?post=86009"},{"taxonomy":"product_metal_color","embeddable":true,"href":"https:\/\/www.tirolergoldschmied.it\/it\/wp-json\/wp\/v2\/product_metal_color?post=86009"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}